{"id":2,"count":3,"description":"","link":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/","name":"Slider","slug":"slider","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slider Archives - Idyllic Creative Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slider Archives - Idyllic Creative Agency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/\" \/>\n<meta property=\"og:site_name\" content=\"Idyllic Creative Agency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/category\\\/slider\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/category\\\/slider\\\/\",\"name\":\"Slider Archives - Idyllic Creative Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/category\\\/slider\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/category\\\/slider\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slider\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#website\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/\",\"name\":\"Idyllic Creative Agency\",\"description\":\"Creative Agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#organization\",\"name\":\"Idyllic Creative Agency\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2017\\\/08\\\/idyllic-creative.png\",\"contentUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2017\\\/08\\\/idyllic-creative.png\",\"width\":560,\"height\":160,\"caption\":\"Idyllic Creative Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic-creative-agency\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slider Archives - Idyllic Creative Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/","og_locale":"en_US","og_type":"article","og_title":"Slider Archives - Idyllic Creative Agency","og_url":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/","og_site_name":"Idyllic Creative Agency","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/","url":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/","name":"Slider Archives - Idyllic Creative Agency","isPartOf":{"@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#website"},"breadcrumb":{"@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/category\/slider\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/"},{"@type":"ListItem","position":2,"name":"Slider"}]},{"@type":"WebSite","@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#website","url":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/","name":"Idyllic Creative Agency","description":"Creative Agency","publisher":{"@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#organization","name":"Idyllic Creative Agency","url":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#\/schema\/logo\/image\/","url":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-content\/uploads\/sites\/25\/2017\/08\/idyllic-creative.png","contentUrl":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-content\/uploads\/sites\/25\/2017\/08\/idyllic-creative.png","width":560,"height":160,"caption":"Idyllic Creative Agency"},"image":{"@id":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.themefreesia.com\/idyllic-creative-agency\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}