{"id":2017,"date":"2017-08-06T07:06:39","date_gmt":"2017-08-06T07:06:39","guid":{"rendered":"http:\/\/demo.themefreesia.com\/idyllic\/?p=2017"},"modified":"2017-08-06T07:06:39","modified_gmt":"2017-08-06T07:06:39","slug":"install-idyllic-powerful-one-click-demo-installer","status":"publish","type":"post","link":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/","title":{"rendered":"Install Idyllic with our powerful one click demo installer."},"content":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Fusce scelerisque iaculis libero, ac pellentesque mi fermentum vitae. Donec ipsum tellus, dapibus at blandit sed, iaculis quis est. Maecenas luctus facilisis lacus, et aliquet arcu cursus vitae. Nulla dolor erat, iaculis in gravida quis, pellentesque sed tortor. Aliquam varius euismod orci venenatis tincidunt. Interdum et malesuada fames ac ante ipsum primis in faucibus. Duis vel pharetra metus, ut pretium mi. Nunc at dolor eros. Aenean tempor viverra risus sit amet condimentum. <!--more--><\/p>\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Fusce scelerisque iaculis libero, ac pellentesque mi fermentum vitae. Donec ipsum tellus, dapibus at blandit sed, iaculis quis est. Maecenas luctus facilisis lacus, et aliquet arcu cursus vitae. Nulla dolor erat, iaculis in gravida quis, pellentesque sed tortor. Aliquam varius euismod orci venenatis tincidunt. Interdum et malesuada fames ac ante ipsum primis in faucibus. Duis vel pharetra metus, ut pretium mi. Nunc at dolor eros. Aenean tempor viverra risus sit amet condimentum.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Fusce scelerisque iaculis libero, ac pellentesque mi fermentum vitae. Donec ipsum tellus, dapibus at blandit sed, iaculis quis est. Maecenas luctus facilisis lacus, et aliquet arcu cursus vitae. Nulla dolor erat, iaculis in gravida quis, pellentesque sed tortor. Aliquam varius euismod orci&hellip; <\/p>\n","protected":false},"author":1,"featured_media":2005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[232],"tags":[203],"class_list":["post-2017","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-hollywood","tag-platinum","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Install Idyllic with our powerful one click demo installer. - Idyllic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Install Idyllic with our powerful one click demo installer. - Idyllic\" \/>\n<meta property=\"og:description\" content=\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Fusce scelerisque iaculis libero, ac pellentesque mi fermentum vitae. Donec ipsum tellus, dapibus at blandit sed, iaculis quis est. Maecenas luctus facilisis lacus, et aliquet arcu cursus vitae. Nulla dolor erat, iaculis in gravida quis, pellentesque sed tortor. Aliquam varius euismod orci&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/\" \/>\n<meta property=\"og:site_name\" content=\"Idyllic\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-06T07:06:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"themefreesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"themefreesia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/\"},\"author\":{\"name\":\"themefreesia\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#\\\/schema\\\/person\\\/ce52b14c73473ec10b55bc3cc03c7ff7\"},\"headline\":\"Install Idyllic with our powerful one click demo installer.\",\"datePublished\":\"2017-08-06T07:06:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/featured-image-2.jpg\",\"keywords\":[\"Platinum\"],\"articleSection\":[\"Hollywood\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/\",\"name\":\"Install Idyllic with our powerful one click demo installer. - Idyllic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/featured-image-2.jpg\",\"datePublished\":\"2017-08-06T07:06:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/featured-image-2.jpg\",\"contentUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/featured-image-2.jpg\",\"width\":1170,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/2017\\\/08\\\/06\\\/install-idyllic-powerful-one-click-demo-installer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Install Idyllic with our powerful one click demo installer.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#website\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/\",\"name\":\"Idyllic\",\"description\":\"Multi Layout Site\",\"publisher\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#organization\",\"name\":\"Idyllic\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/idyllic-logo.png\",\"contentUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2017\\\/08\\\/idyllic-logo.png\",\"width\":300,\"height\":160,\"caption\":\"Idyllic\"},\"image\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/#\\\/schema\\\/person\\\/ce52b14c73473ec10b55bc3cc03c7ff7\",\"name\":\"themefreesia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g\",\"caption\":\"themefreesia\"},\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/idyllic\\\/author\\\/demo_themefreesia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Install Idyllic with our powerful one click demo installer. - Idyllic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/","og_locale":"en_US","og_type":"article","og_title":"Install Idyllic with our powerful one click demo installer. - Idyllic","og_description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Fusce scelerisque iaculis libero, ac pellentesque mi fermentum vitae. Donec ipsum tellus, dapibus at blandit sed, iaculis quis est. Maecenas luctus facilisis lacus, et aliquet arcu cursus vitae. Nulla dolor erat, iaculis in gravida quis, pellentesque sed tortor. Aliquam varius euismod orci&hellip;","og_url":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/","og_site_name":"Idyllic","article_published_time":"2017-08-06T07:06:39+00:00","og_image":[{"width":1170,"height":640,"url":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","type":"image\/jpeg"}],"author":"themefreesia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"themefreesia","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#article","isPartOf":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/"},"author":{"name":"themefreesia","@id":"https:\/\/demo.themefreesia.com\/idyllic\/#\/schema\/person\/ce52b14c73473ec10b55bc3cc03c7ff7"},"headline":"Install Idyllic with our powerful one click demo installer.","datePublished":"2017-08-06T07:06:39+00:00","mainEntityOfPage":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/"},"wordCount":169,"publisher":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/#organization"},"image":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#primaryimage"},"thumbnailUrl":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","keywords":["Platinum"],"articleSection":["Hollywood"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/","url":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/","name":"Install Idyllic with our powerful one click demo installer. - Idyllic","isPartOf":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/#website"},"primaryImageOfPage":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#primaryimage"},"image":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#primaryimage"},"thumbnailUrl":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","datePublished":"2017-08-06T07:06:39+00:00","breadcrumb":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#primaryimage","url":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","contentUrl":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","width":1170,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/demo.themefreesia.com\/idyllic\/2017\/08\/06\/install-idyllic-powerful-one-click-demo-installer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demo.themefreesia.com\/idyllic\/"},{"@type":"ListItem","position":2,"name":"Install Idyllic with our powerful one click demo installer."}]},{"@type":"WebSite","@id":"https:\/\/demo.themefreesia.com\/idyllic\/#website","url":"https:\/\/demo.themefreesia.com\/idyllic\/","name":"Idyllic","description":"Multi Layout Site","publisher":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demo.themefreesia.com\/idyllic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/demo.themefreesia.com\/idyllic\/#organization","name":"Idyllic","url":"https:\/\/demo.themefreesia.com\/idyllic\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demo.themefreesia.com\/idyllic\/#\/schema\/logo\/image\/","url":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/idyllic-logo.png","contentUrl":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/idyllic-logo.png","width":300,"height":160,"caption":"Idyllic"},"image":{"@id":"https:\/\/demo.themefreesia.com\/idyllic\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/demo.themefreesia.com\/idyllic\/#\/schema\/person\/ce52b14c73473ec10b55bc3cc03c7ff7","name":"themefreesia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/07c08f415b191085bbb1425839bdc21aad39160e069b39296ae263e26368d138?s=96&d=mm&r=g","caption":"themefreesia"},"url":"https:\/\/demo.themefreesia.com\/idyllic\/author\/demo_themefreesia\/"}]}},"jetpack_featured_media_url":"https:\/\/demo.themefreesia.com\/idyllic\/wp-content\/uploads\/sites\/22\/2017\/08\/featured-image-2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p92LCZ-wx","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/posts\/2017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/comments?post=2017"}],"version-history":[{"count":1,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/posts\/2017\/revisions"}],"predecessor-version":[{"id":2018,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/posts\/2017\/revisions\/2018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/media\/2005"}],"wp:attachment":[{"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/media?parent=2017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/categories?post=2017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/demo.themefreesia.com\/idyllic\/wp-json\/wp\/v2\/tags?post=2017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}