{"id":5,"count":3,"description":"","link":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/","name":"Commerce","slug":"commerce","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Commerce Archives - TrustNews Plus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commerce Archives - TrustNews Plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/\" \/>\n<meta property=\"og:site_name\" content=\"TrustNews Plus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/category\\\/commerce\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/category\\\/commerce\\\/\",\"name\":\"Commerce Archives - TrustNews Plus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/category\\\/commerce\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/category\\\/commerce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commerce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#website\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/\",\"name\":\"TrustNews Plus\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#organization\",\"name\":\"TrustNews Plus\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/wp-content\\\/uploads\\\/sites\\\/77\\\/2020\\\/12\\\/tnprologo.png\",\"contentUrl\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/wp-content\\\/uploads\\\/sites\\\/77\\\/2020\\\/12\\\/tnprologo.png\",\"width\":515,\"height\":120,\"caption\":\"TrustNews Plus\"},\"image\":{\"@id\":\"https:\\\/\\\/demo.themefreesia.com\\\/trustnews-plus\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commerce Archives - TrustNews Plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/","og_locale":"en_US","og_type":"article","og_title":"Commerce Archives - TrustNews Plus","og_url":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/","og_site_name":"TrustNews Plus","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/","url":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/","name":"Commerce Archives - TrustNews Plus","isPartOf":{"@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#website"},"breadcrumb":{"@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/category\/commerce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demo.themefreesia.com\/trustnews-plus\/"},{"@type":"ListItem","position":2,"name":"Commerce"}]},{"@type":"WebSite","@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#website","url":"https:\/\/demo.themefreesia.com\/trustnews-plus\/","name":"TrustNews Plus","description":"","publisher":{"@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demo.themefreesia.com\/trustnews-plus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#organization","name":"TrustNews Plus","url":"https:\/\/demo.themefreesia.com\/trustnews-plus\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#\/schema\/logo\/image\/","url":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-content\/uploads\/sites\/77\/2020\/12\/tnprologo.png","contentUrl":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-content\/uploads\/sites\/77\/2020\/12\/tnprologo.png","width":515,"height":120,"caption":"TrustNews Plus"},"image":{"@id":"https:\/\/demo.themefreesia.com\/trustnews-plus\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.themefreesia.com\/trustnews-plus\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}